{"id":46775,"date":"2021-12-28T08:00:15","date_gmt":"2021-12-28T11:00:15","guid":{"rendered":"https:\/\/pointer.com.br\/blog\/?p=46775"},"modified":"2021-12-28T08:00:15","modified_gmt":"2021-12-28T11:00:15","slug":"importancia-de-conferir-revestimentos-e-materiais","status":"publish","type":"post","link":"https:\/\/pointer.com.br\/blog\/importancia-de-conferir-revestimentos-e-materiais\/","title":{"rendered":"A import\u00e2ncia de conferir quando receber os revestimentos (e outros materiais) na obra"},"content":{"rendered":"<p>Para muita gente, fazer uma obra representa a realiza\u00e7\u00e3o de um sonho. Mas j\u00e1 imaginou perceber rachaduras ou defeitos no material depois da instala\u00e7\u00e3o? Ou que foi assentado um revestimento diferente daquele escolhido na loja? Para evitar esse tipo de frustra\u00e7\u00e3o, \u00e9 importante conferir revestimentos e outros itens, como lou\u00e7as e metais.<\/p>\n<p>D\u00e1 trabalho? Dependendo da quantidade, sim. Mas vale a pena para garantir um resultado final perfeito, sem perrengues graves no processo. Afinal, revestimento assentado \u00e9 revestimento aceito. A seguir, vamos te explicar tudo o que voc\u00ea precisa verificar e como fazer isso, para resolver os problemas com agilidade e garantia.\u00a0<\/p>\n<h2>Como conferir revestimentos e outros materiais da obra<\/h2>\n<p>N\u00e3o importa se voc\u00ea retirou o produto na loja ou recebeu em casa, a etapa da confer\u00eancia \u00e9 essencial para garantir que o resultado final n\u00e3o seja comprometido. Verifique cada detalhe de lou\u00e7as, metais, rejuntes, argamassas, tubula\u00e7\u00f5es, al\u00e9m de conferir todas as pe\u00e7as dos revestimentos. Sim, estamos sugerindo voc\u00ea abrir todas as embalagens e checar item por item. Para isso, verifique:<\/p>\n<h3>Embalagem<\/h3>\n<p>Ao receber os materiais, veja se as embalagens est\u00e3o inteiras e fechadas. Se estiverem violadas, n\u00e3o receba o produto, pois pode ser que as pe\u00e7as estejam danificadas. Tamb\u00e9m confira na embalagem se consta o nome e as especifica\u00e7\u00f5es t\u00e9cnicas do produto que voc\u00ea comprou. Erros acontecem e, \u00e0s vezes, a loja ou a transportadora podem te entregar o produto errado.<\/p>\n<h3>Nota fiscal<\/h3>\n<p>Tamb\u00e9m \u00e9 importante conferir se o que voc\u00ea recebeu corresponde ao que comprou. Verifique se o nome do produto \u00e9 o mesmo da embalagem, al\u00e9m de observar a cor, o <a data-type=\"LINK\" href=\"https:\/\/pointer.com.br\/blog\/ceramica-esmaltada\/\" target=\"_blank\" rel=\"noopener\"><u>tipo de acabamento<\/u><\/a>, o tamanho e, claro, a quantidade.<\/p>\n<h3>Produto<\/h3>\n<p>Por fim, mesmo que voc\u00ea n\u00e3o v\u00e1 instalar assim que receber, \u00e9 importante abrir as embalagens para saber se est\u00e1 tudo certo com o material. Desse jeito, voc\u00ea n\u00e3o perde o prazo de troca ou devolu\u00e7\u00e3o caso algo esteja danificado.<\/p>\n<figure class=\"gh-styles-m__figureContainer\" style=\"float: undefined;text-align: center\"><img decoding=\"async\" alt=\"\" class=\"gh-styles-m__figureContainer-image\" height=\"auto\" src=\"https:\/\/pointer.com.br\/blog\/wp-content\/uploads\/2021\/12\/conferirrevestimentosemateriaisdeobra-scaled.jpeg\" title=\"\" width=\"100%\" \/><figcaption class=\"gh-styles-m__figureContainer-caption\"><\/figcaption><\/figure>\n<p style=\"text-align:center\"><em>Verificar embalagem, nota fiscal e o produto s\u00e3o formas de garantir que voc\u00ea recebeu exatamente o que comprou (Foto: <\/em><a data-type=\"LINK\" href=\"https:\/\/unsplash.com\/photos\/EvtlbRUm66A\" target=\"_blank\" rel=\"noopener\"><em>Oxana Melis<\/em><\/a><em>\/Unsplash)<\/em><\/p>\n<h2>Conferir revestimentos \u00e9 passo indispens\u00e1vel<\/h2>\n<p>E j\u00e1 que esse \u00e9 o blog de uma marca de revestimentos cer\u00e2micos, vamos falar mais especificamente da confer\u00eancia deles. Se voc\u00ea instalar um revestimento com defeito, ou que veio errado, dificilmente haver\u00e1 troca. Revestimento assentado \u00e9 revestimento aceito.<\/p>\n<p>Por outro lado, se voc\u00ea logo perceber o defeito ou erro, a loja e\/ou o fabricante rapidamente poder\u00e3o fazer a corre\u00e7\u00e3o. Final feliz para a sua obra! O respons\u00e1vel pela confer\u00eancia \u00e9 o dono da obra &#8211; n\u00e3o confie na m\u00e3o de obra contratada, que pode n\u00e3o dar tanta aten\u00e7\u00e3o como voc\u00ea.<\/p>\n<p>Entre os problemas mais comuns com revestimentos est\u00e3o:\u00a0<\/p>\n<ul>\n<li>Vir o revestimento errado;\u00a0<\/li>\n<li>O revestimento chegar com pe\u00e7as quebradas;<\/li>\n<li>Algumas pec\u0327as apresentarem defeitos;<\/li>\n<li>O revestimento vir no formato ou acabamento diferente do que voce\u0302 comprou.<\/li>\n<\/ul>\n<p>E se voce\u0302 na\u0303o supervisiona, manda assentar o revestimento e so\u0301 depois percebe que tem algo errado, dificilmente conseguir\u00e1 trocar. A loja e a f\u00e1bricante, em geral, n\u00e3o far\u00e3o a troca de um revestimento j\u00e1 assentado.<\/p>\n<figure class=\"gh-styles-m__figureContainer\" style=\"float: undefined;text-align: center\"><img decoding=\"async\" alt=\"conferir revestimentos\" class=\"gh-styles-m__figureContainer-image\" height=\"auto\" src=\"https:\/\/pointer.com.br\/blog\/wp-content\/uploads\/2021\/12\/conferirrevestimentosnaobra-scaled.jpeg\" title=\"\" width=\"100%\" \/><figcaption class=\"gh-styles-m__figureContainer-caption\"><\/figcaption><\/figure>\n<p style=\"text-align:center\"><em>Materiais de obra como lou\u00e7as, metais e revestimentos precisam de confer\u00eancia. Na imagem, revestimentos cer\u00e2micos escolhidos foram Stellar Grey, os lan\u00e7amentos Mandala Blu e Piquet Blanc e o Filete Gray, da linha Zeppelin<\/em><\/p>\n<h2>Armazenamento correto dos materiais evita problemas<\/h2>\n<p>Depois de conferir revestimentos e outros materiais, voc\u00ea precisa armazenar tudo corretamente para evitar quebras e outros danos durante o tempo que ficarem guardados. Confira algumas dicas para n\u00e3o errar:<\/p>\n<ul>\n<li><u>Revestimentos de grandes formatos<\/u> precisam ser carregados por duas pessoas, cada uma segurando em uma extremidade. Isso evita que a pe\u00e7a trinque ou quebre;<\/li>\n<li>Separe os produtos de acordo com as suas caracter\u00edsticas para n\u00e3o confundir na hora da instala\u00e7\u00e3o;<\/li>\n<li>Estoque em um local sem umidade para n\u00e3o estragar seus produtos;<\/li>\n<li>Armazene as caixas na vertical ou na posi\u00e7\u00e3o indicada pelo fabricante para evitar que o material quebre.<\/li>\n<\/ul>\n<p>Agora, se voc\u00ea ainda n\u00e3o comprou os revestimentos cer\u00e2micos da obra, a gente tem dicas importantes para essa escolha. Descubra <a data-type=\"LINK\" href=\"https:\/\/pointer.com.br\/blog\/revestimento-para-casa\/\" target=\"_blank\" rel=\"noopener\"><u>como escolher o revestimento ideal para cada ambiente da casa<\/u><\/a>!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Conferir revestimentos e outros materiais \u00e9 fundamental para evitar problemas. Saiba o que voc\u00ea precisa verificar!<\/p>\n","protected":false},"author":0,"featured_media":47225,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"class_list":["post-46775","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dicas-pointer"],"acf":[],"_links":{"self":[{"href":"https:\/\/pointer.com.br\/blog\/wp-json\/wp\/v2\/posts\/46775","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pointer.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pointer.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/pointer.com.br\/blog\/wp-json\/wp\/v2\/comments?post=46775"}],"version-history":[{"count":12,"href":"https:\/\/pointer.com.br\/blog\/wp-json\/wp\/v2\/posts\/46775\/revisions"}],"predecessor-version":[{"id":47226,"href":"https:\/\/pointer.com.br\/blog\/wp-json\/wp\/v2\/posts\/46775\/revisions\/47226"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pointer.com.br\/blog\/wp-json\/wp\/v2\/media\/47225"}],"wp:attachment":[{"href":"https:\/\/pointer.com.br\/blog\/wp-json\/wp\/v2\/media?parent=46775"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pointer.com.br\/blog\/wp-json\/wp\/v2\/categories?post=46775"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pointer.com.br\/blog\/wp-json\/wp\/v2\/tags?post=46775"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}