{"id":41175,"date":"2018-09-17T18:11:33","date_gmt":"2018-09-17T21:11:33","guid":{"rendered":"https:\/\/pointer.com.br\/blog\/?p=41175"},"modified":"2018-09-18T16:16:06","modified_gmt":"2018-09-18T19:16:06","slug":"a-vez-dos-superceramicos-conheca-as-vantagens-dessa-nova-categoria-de-revestimento","status":"publish","type":"post","link":"https:\/\/pointer.com.br\/blog\/a-vez-dos-superceramicos-conheca-as-vantagens-dessa-nova-categoria-de-revestimento\/","title":{"rendered":"A vez dos supercer\u00e2micos; conhe\u00e7a as vantagens dessa nova categoria de revestimento!"},"content":{"rendered":"<p><a href=\"https:\/\/pointer.com.br\/blog\/democratizacao-design-e-sustentabilidade\/\" target=\"_blank\" rel=\"noopener\">A casa do futuro ser\u00e1 uma casa cada vez mais democr\u00e1tica e sustent\u00e1vel. <\/a>\u00c9 dentro desse conceito de ambiente e estilo de vida, com foco na personaliza\u00e7\u00e3o, que o<strong><i> supercer\u00e2mico<\/i><\/strong> chega ao mercado. \u00c9 uma nova categoria de revestimento criada pela Pointer, com o DNA da marca Portobello. Uma proposta inovadora para os consumidores, por apresentar caracter\u00edsticas tanto t\u00e9cnicas quanto est\u00e9ticas, que o diferenciam da <a href=\"https:\/\/pointer.com.br\/blog\/porcelanato-ou-ceramica\/\" target=\"_blank\" rel=\"noopener\">cer\u00e2mica e do porcelanato,<\/a>\u00a0revestimentos j\u00e1 bastante conhecidos pelo consumidor.<\/p>\n<p>O <b><i>supercer\u00e2mico<\/i><\/b> nasce como a evolu\u00e7\u00e3o da cer\u00e2mica tradicional, por oferecer o <a href=\"https:\/\/pointer.com.br\/blog\/ceramica-de-z\/\" target=\"_blank\" rel=\"noopener\">melhor custo-benef\u00edcio<\/a> para quem pensa em decorar novos ambientes: a escolha \u00e9 pelo excelente design das pe\u00e7as, durabilidade, valor do produto e custo de instala\u00e7\u00e3o (n\u00f3s vamos explicar tudo isso logo mais!). A nova proposta desse revestimento foi criada sob medida para projetos residenciais e comerciais com tr\u00e1fego leve.<\/p>\n<p>Veja as in\u00fameras vantagens que essa nova categoria de revestimento oferece. <a href=\"https:\/\/www.youtube.com\/watch?v=5MLHMIo-zDc&amp;feature=youtu.be\" target=\"_blank\" rel=\"noopener\"><b>Mas, antes, assista aqui ao v\u00eddeo de lan\u00e7amento!<\/b><\/a><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-41178 size-full\" src=\"https:\/\/pointer.com.br\/blog\/wp-content\/uploads\/2018\/09\/grandes-formatos-supercer\u00e2mico-pointer.jpg\" alt=\"\" width=\"1751\" height=\"799\" srcset=\"https:\/\/pointer.com.br\/blog\/wp-content\/uploads\/2018\/09\/grandes-formatos-supercer\u00e2mico-pointer.jpg 1751w, https:\/\/pointer.com.br\/blog\/wp-content\/uploads\/2018\/09\/grandes-formatos-supercer\u00e2mico-pointer-300x137.jpg 300w, https:\/\/pointer.com.br\/blog\/wp-content\/uploads\/2018\/09\/grandes-formatos-supercer\u00e2mico-pointer-768x350.jpg 768w, https:\/\/pointer.com.br\/blog\/wp-content\/uploads\/2018\/09\/grandes-formatos-supercer\u00e2mico-pointer-1024x467.jpg 1024w\" sizes=\"auto, (max-width: 1751px) 100vw, 1751px\" \/><\/p>\n<ul>\n<li><a href=\"https:\/\/pointer.com.br\/blog\/grandes-formatos-de-revestimento\/\"><b>grandes formatos<\/b><\/a><b>:\u00a0<\/b>a sensa\u00e7\u00e3o no mercado, o queridinho dos arquitetos. Pela primeira vez, s\u00e3o produzidas pe\u00e7as em grandes dimens\u00f5es com pre\u00e7o acess\u00edvel ao consumidor. Nos tamanhos 15&#215;90, 45&#215;90 e, agora, <b>80x80cm<\/b>, os <strong>supercer\u00e2micos<\/strong> permitem criar superf\u00edcies cont\u00ednuas, ampliar o ambiente e promover agilidade da instala\u00e7\u00e3o das pe\u00e7as na hora da obra;<\/li>\n<\/ul>\n<ul>\n<li><a href=\"https:\/\/pointer.com.br\/blog\/acabamento-retificado\/\"><b>acabamento retificado<\/b><\/a>: diferente do bold, \u00e9 um acabamento que utiliza junta m\u00ednima de 1,5mm. Assim, gera mais economia de rejunte e facilita a limpeza dos <strong>supercer\u00e2micos<\/strong>. Al\u00e9m disso, h\u00e1 ganho est\u00e9tico no ambiente, j\u00e1 que o acabamento deixa o rejunte menos aparente.<\/li>\n<\/ul>\n<ul>\n<li><a href=\"https:\/\/pointer.com.br\/blog\/pointer-apresenta-ceramicas-com-mais-design-e-possibilidades-aos-ambientes\/\"><b>DNA Portobello<\/b><\/a><b>:\u00a0<\/b>o <b>supercer\u00e2mico<\/b> da Pointer nasce a partir do DNA da Portobello, que combina performance, qualidade, desempenho com est\u00e9tica, inova\u00e7\u00e3o e design. Tudo isso realizado com a participa\u00e7\u00e3o de uma equipe criativa que pesquisa constantemente por materiais, tend\u00eancias e tecnologia.<img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-41183 \" src=\"https:\/\/pointer.com.br\/blog\/wp-content\/uploads\/2018\/09\/10mm-espessura-supercer\u00e2mico-pointer.png\" alt=\"\" width=\"483\" height=\"236\" srcset=\"https:\/\/pointer.com.br\/blog\/wp-content\/uploads\/2018\/09\/10mm-espessura-supercer\u00e2mico-pointer.png 739w, https:\/\/pointer.com.br\/blog\/wp-content\/uploads\/2018\/09\/10mm-espessura-supercer\u00e2mico-pointer-300x147.png 300w\" sizes=\"auto, (max-width: 483px) 100vw, 483px\" \/><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul>\n<li><b><a href=\"https:\/\/www.pointer.com.br\/revestimentos\" target=\"_blank\" rel=\"noopener\">maior robustez<\/a>: <\/b>os<b> <\/b><b><i>supercer\u00e2micos<\/i><\/b> possuem a maior espessura do mercado, de 10mm!<\/li>\n<\/ul>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-41184 \" src=\"https:\/\/pointer.com.br\/blog\/wp-content\/uploads\/2018\/09\/alta-resist\u00eancia-supercer\u00e2mico-pointer.jpg\" alt=\"\" width=\"495\" height=\"247\" srcset=\"https:\/\/pointer.com.br\/blog\/wp-content\/uploads\/2018\/09\/alta-resist\u00eancia-supercer\u00e2mico-pointer.jpg 971w, https:\/\/pointer.com.br\/blog\/wp-content\/uploads\/2018\/09\/alta-resist\u00eancia-supercer\u00e2mico-pointer-300x150.jpg 300w, https:\/\/pointer.com.br\/blog\/wp-content\/uploads\/2018\/09\/alta-resist\u00eancia-supercer\u00e2mico-pointer-768x384.jpg 768w\" sizes=\"auto, (max-width: 495px) 100vw, 495px\" \/><\/p>\n<ul>\n<li><b><a href=\"https:\/\/pointer.com.br\/blog\/rejuntar-pisos-com-resistencia-ao-escorregamento\/\" target=\"_blank\" rel=\"noopener\">alta resist\u00eancia<\/a>: os supercer\u00e2micos\u00a0<\/b>suportam at\u00e9 4 toneladas por m\u00b2; \u00e9 ideal para uso na casa toda e em ambientes comerciais com tr\u00e1fego leve. Tamb\u00e9m possuem resist\u00eancias a:<\/li>\n<\/ul>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-41186\" src=\"https:\/\/pointer.com.br\/blog\/wp-content\/uploads\/2018\/09\/resistente-ao-impacto-supercer\u00e2mico-pointer.jpg\" alt=\"\" width=\"495\" height=\"276\" srcset=\"https:\/\/pointer.com.br\/blog\/wp-content\/uploads\/2018\/09\/resistente-ao-impacto-supercer\u00e2mico-pointer.jpg 975w, https:\/\/pointer.com.br\/blog\/wp-content\/uploads\/2018\/09\/resistente-ao-impacto-supercer\u00e2mico-pointer-300x167.jpg 300w, https:\/\/pointer.com.br\/blog\/wp-content\/uploads\/2018\/09\/resistente-ao-impacto-supercer\u00e2mico-pointer-768x428.jpg 768w\" sizes=\"auto, (max-width: 495px) 100vw, 495px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-41188\" src=\"https:\/\/pointer.com.br\/blog\/wp-content\/uploads\/2018\/09\/resist\u00eancia-ao-risco-supercer\u00e2mico-pointer.jpg\" alt=\"\" width=\"495\" height=\"278\" srcset=\"https:\/\/pointer.com.br\/blog\/wp-content\/uploads\/2018\/09\/resist\u00eancia-ao-risco-supercer\u00e2mico-pointer.jpg 971w, https:\/\/pointer.com.br\/blog\/wp-content\/uploads\/2018\/09\/resist\u00eancia-ao-risco-supercer\u00e2mico-pointer-300x169.jpg 300w, https:\/\/pointer.com.br\/blog\/wp-content\/uploads\/2018\/09\/resist\u00eancia-ao-risco-supercer\u00e2mico-pointer-768x432.jpg 768w\" sizes=\"auto, (max-width: 495px) 100vw, 495px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-41189\" src=\"https:\/\/pointer.com.br\/blog\/wp-content\/uploads\/2018\/09\/resistente-altas-temperaturas-supercer\u00e2mico-pointer.jpg\" alt=\"\" width=\"495\" height=\"285\" srcset=\"https:\/\/pointer.com.br\/blog\/wp-content\/uploads\/2018\/09\/resistente-altas-temperaturas-supercer\u00e2mico-pointer.jpg 953w, https:\/\/pointer.com.br\/blog\/wp-content\/uploads\/2018\/09\/resistente-altas-temperaturas-supercer\u00e2mico-pointer-300x173.jpg 300w, https:\/\/pointer.com.br\/blog\/wp-content\/uploads\/2018\/09\/resistente-altas-temperaturas-supercer\u00e2mico-pointer-768x442.jpg 768w\" sizes=\"auto, (max-width: 495px) 100vw, 495px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p><b>E as vantagens n\u00e3o param. Veja mais:<\/b><\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li><strong><a href=\"https:\/\/pointer.com.br\/blog\/revestimento-para-quartos-com-umidade\/\" target=\"_blank\" rel=\"noopener\">impermeabilidade<\/a>:<\/strong> os <b><i>supercer\u00e2micos<\/i><\/b> possuem superf\u00edcie 100% imperme\u00e1vel<\/li>\n<\/ul>\n<ul>\n<li><b><a href=\"https:\/\/www.pointer.com.br\/especiais\/colecao-2018\" target=\"_blank\" rel=\"noopener\">mais economia<\/a>:<\/b> possibilita o uso de argamassa simples (tipo AC1), menos rejunte e maior produtividade na aplica\u00e7\u00e3o dos grandes formatos.<\/li>\n<\/ul>\n<ul>\n<li><b><a href=\"https:\/\/www.pointer.com.br\/sobre-a-pointer\" target=\"_blank\" rel=\"noopener\">sustentabilidade<\/a>:<\/b> possui processo produtivo inteligente, de alta tecnologia e baixo impacto ambiental. Tudo isso gera racionalidade no uso da \u00e1gua, de recursos energ\u00e9ticos e de mat\u00e9ria prima.<\/li>\n<\/ul>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-41192 size-full\" src=\"https:\/\/pointer.com.br\/blog\/wp-content\/uploads\/2018\/09\/design-supercer\u00e2mico-pointer.jpg\" alt=\"\" width=\"1297\" height=\"375\" srcset=\"https:\/\/pointer.com.br\/blog\/wp-content\/uploads\/2018\/09\/design-supercer\u00e2mico-pointer.jpg 1297w, https:\/\/pointer.com.br\/blog\/wp-content\/uploads\/2018\/09\/design-supercer\u00e2mico-pointer-300x87.jpg 300w, https:\/\/pointer.com.br\/blog\/wp-content\/uploads\/2018\/09\/design-supercer\u00e2mico-pointer-768x222.jpg 768w, https:\/\/pointer.com.br\/blog\/wp-content\/uploads\/2018\/09\/design-supercer\u00e2mico-pointer-1024x296.jpg 1024w\" sizes=\"auto, (max-width: 1297px) 100vw, 1297px\" \/><\/p>\n<ul>\n<li><b><a href=\"https:\/\/pointer.com.br\/blog\/estilo-urbano\/\" target=\"_blank\" rel=\"noopener\">Design aut\u00eantico<\/a>:<\/b> portf\u00f3lio com materiais da arquitetura e decorados, criados pela equipe criativa da Pointer, com DNA Portobello. Os <b><i>supercer\u00e2micos<\/i><\/b> possibilitam m\u00faltiplas possibilidades de personaliza\u00e7\u00e3o no ambiente, al\u00e9m de \u00a0possuir pe\u00e7as com grande varia\u00e7\u00e3o de desenhos (veja acima!).<\/li>\n<\/ul>\n<h3><b>Mas o que diferencia dos demais revestimentos?<\/b><\/h3>\n<p>Este infogr\u00e1fico abaixo mostra por que os supercer\u00e2micos oferecem o melhor custo-benef\u00edcio dos revestimentos:<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-41194 size-full\" src=\"https:\/\/pointer.com.br\/blog\/wp-content\/uploads\/2018\/09\/compara\u00e7\u00e3o-com-cer\u00e2micas-e-porcelanatos-supercer\u00e2micos.jpg\" alt=\"\" width=\"1661\" height=\"613\" srcset=\"https:\/\/pointer.com.br\/blog\/wp-content\/uploads\/2018\/09\/compara\u00e7\u00e3o-com-cer\u00e2micas-e-porcelanatos-supercer\u00e2micos.jpg 1661w, https:\/\/pointer.com.br\/blog\/wp-content\/uploads\/2018\/09\/compara\u00e7\u00e3o-com-cer\u00e2micas-e-porcelanatos-supercer\u00e2micos-300x111.jpg 300w, https:\/\/pointer.com.br\/blog\/wp-content\/uploads\/2018\/09\/compara\u00e7\u00e3o-com-cer\u00e2micas-e-porcelanatos-supercer\u00e2micos-768x283.jpg 768w, https:\/\/pointer.com.br\/blog\/wp-content\/uploads\/2018\/09\/compara\u00e7\u00e3o-com-cer\u00e2micas-e-porcelanatos-supercer\u00e2micos-1024x378.jpg 1024w\" sizes=\"auto, (max-width: 1661px) 100vw, 1661px\" \/><\/p>\n<p>Dispon\u00edvel nos formatos 80x80cm, 45x90cm e 15x90cm, o supercer\u00e2mico aparece dividido em 14 diferentes linhas, que reproduzem materiais essenciais da arquitetura, como m\u00e1rmores, pedras naturais, cimento, madeira e elementos decorados, com e sem textura, e prometem dar origem a ambientes \u00fanicos.<\/p>\n<p>O que achou dessa <strong>supernovidade<\/strong> da Pointer? Deixe aqui seu coment\u00e1rio e continue nos acompanhando! Ah,\u00a0 e paralelo ao supercer\u00e2mico, a Pointer tamb\u00e9m acaba de lan\u00e7ar uma nova cole\u00e7\u00e3o; <a href=\"https:\/\/pointer.com.br\/blog\/superceramicos-80x80-relevos-geometricos-e-tijolinhos-marcam-a-nova-colecao-da-pointer-confira\/\" target=\"_blank\" rel=\"noopener\">conhe\u00e7a agora<\/a>!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A casa do futuro ser\u00e1 uma casa cada vez mais democr\u00e1tica e sustent\u00e1vel. \u00c9 dentro desse conceito de ambiente e estilo de vida, com foco na personaliza\u00e7\u00e3o, que o supercer\u00e2mico chega ao mercado. \u00c9 uma [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":41181,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22],"tags":[],"class_list":["post-41175","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-novidades"],"acf":[],"_links":{"self":[{"href":"https:\/\/pointer.com.br\/blog\/wp-json\/wp\/v2\/posts\/41175","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pointer.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pointer.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pointer.com.br\/blog\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/pointer.com.br\/blog\/wp-json\/wp\/v2\/comments?post=41175"}],"version-history":[{"count":50,"href":"https:\/\/pointer.com.br\/blog\/wp-json\/wp\/v2\/posts\/41175\/revisions"}],"predecessor-version":[{"id":41284,"href":"https:\/\/pointer.com.br\/blog\/wp-json\/wp\/v2\/posts\/41175\/revisions\/41284"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pointer.com.br\/blog\/wp-json\/wp\/v2\/media\/41181"}],"wp:attachment":[{"href":"https:\/\/pointer.com.br\/blog\/wp-json\/wp\/v2\/media?parent=41175"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pointer.com.br\/blog\/wp-json\/wp\/v2\/categories?post=41175"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pointer.com.br\/blog\/wp-json\/wp\/v2\/tags?post=41175"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}